{"id":16846,"date":"2023-05-03T11:57:03","date_gmt":"2023-05-03T14:57:03","guid":{"rendered":"https:\/\/mulhervitrola.com.br\/blog\/?p=16846"},"modified":"2023-05-03T11:57:08","modified_gmt":"2023-05-03T14:57:08","slug":"dolores-sumiu","status":"publish","type":"post","link":"https:\/\/mulhervitrola.com.br\/blog\/dolores-sumiu\/","title":{"rendered":"Dolores sumiu."},"content":{"rendered":"\n<p class=\"has-text-align-justify\">Para contar a hist\u00f3ria de Dolores, preciso contar antes sobre o Sr. Nelson. <\/p>\n\n\n\n<p class=\"has-text-align-justify\">O Sr. Nelson era um artista de Nova Igua\u00e7u. Al\u00e9m de pintor de belos quadros, era professor de artes e idiomas. Apreciador de m\u00fasica espanhola e italiana e colecionador de discos de vinil. Tamb\u00e9m resgatava gatinhos de rua e todas as manh\u00e3s, sentava-se na beirada da sua varanda, limpava e alimentava, com muita paci\u00eancia, os que eram muito filhotes, at\u00e9 que ficassem fortes o suficiente para ganharem outro lar. Para as aulas, fazia quest\u00e3o de fabricar seu pr\u00f3prio giz, e desenhava cheio de destreza no quadro-negro em sua sala de jantar, que tamb\u00e9m era sala de aula, adicionando aos ensinamentos sua caligrafia invej\u00e1vel. Aos s\u00e1bados, bem cedinho, costumava ir \u00e0 feira, preparava o almo\u00e7o e cuidava da esposa Jandyra: a alimentava, dava banho e fazia quest\u00e3o de narrar tudo que estava acontecendo com riqueza de detalhes, pois Jandyra era cega h\u00e1 d\u00e9cadas. <\/p>\n\n\n\n<p class=\"has-text-align-justify\">Em alguns finais de semana, sr. Nelson costumava receber a neta que havia rec\u00e9m conhecido e que adorava desenhar, e empolgado com seus gostos e curiosidades em comum, sempre a presenteava com apostilas com refer\u00eancias de desenho. A ensinava como desenhar um nariz humano e mostrava com orgulho a mesa revestida de azulejos que ele mesmo fez. Dizia, com carinho e sorridente, todas as vezes ao se despedir: &#8220;Um dia, voc\u00ea tamb\u00e9m ser\u00e1 uma desenhista&#8221;.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">O Sr. Nelson era meu av\u00f4, ainda que de considera\u00e7\u00e3o, que faleceu em algum m\u00eas no ano de 92. Eu tinha 7 anos. Meus pais receberam a not\u00edcia atrav\u00e9s de um telegrama. Na \u00e9poca, me senti injusti\u00e7ada. Eu mal pude desfrutar da presen\u00e7a dele. Hoje, h\u00e1 mais de 30 anos ap\u00f3s o ocorrido, a imagem e o afeto do meu av\u00f4 ainda reverberam intensamente em mim. Como pode algo t\u00e3o r\u00e1pido e terno ter tido tanta consist\u00eancia ap\u00f3s todos esses anos?<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" width=\"2560\" height=\"1439\" src=\"https:\/\/i0.wp.com\/mulhervitrola.com.br\/blog\/wp-content\/uploads\/2023\/05\/IMG_20230503_085942358-scaled.jpg?resize=2560%2C1439&#038;ssl=1\" alt=\"\" class=\"wp-image-16848\" srcset=\"https:\/\/i0.wp.com\/mulhervitrola.com.br\/blog\/wp-content\/uploads\/2023\/05\/IMG_20230503_085942358-scaled.jpg?w=2560&amp;ssl=1 2560w, https:\/\/i0.wp.com\/mulhervitrola.com.br\/blog\/wp-content\/uploads\/2023\/05\/IMG_20230503_085942358-scaled.jpg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/mulhervitrola.com.br\/blog\/wp-content\/uploads\/2023\/05\/IMG_20230503_085942358-scaled.jpg?resize=620%2C349&amp;ssl=1 620w, https:\/\/i0.wp.com\/mulhervitrola.com.br\/blog\/wp-content\/uploads\/2023\/05\/IMG_20230503_085942358-scaled.jpg?resize=768%2C432&amp;ssl=1 768w, https:\/\/i0.wp.com\/mulhervitrola.com.br\/blog\/wp-content\/uploads\/2023\/05\/IMG_20230503_085942358-scaled.jpg?resize=1536%2C864&amp;ssl=1 1536w, https:\/\/i0.wp.com\/mulhervitrola.com.br\/blog\/wp-content\/uploads\/2023\/05\/IMG_20230503_085942358-scaled.jpg?resize=2048%2C1152&amp;ssl=1 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><figcaption class=\"wp-element-caption\">Um 3&#215;4 do meu av\u00f4 Nelson. Ao fundo, artes minhas e tamb\u00e9m artes do meu av\u00f4. <\/figcaption><\/figure>\n\n\n\n<p class=\"has-text-align-justify\">Recebi os quadros que meu av\u00f4 pintava recentemente, ap\u00f3s o falecimento de uma tia. Perguntei pro meu tio se ele tinha, por acaso, alguma foto do Sr. Nelson, j\u00e1 que tudo que eu possu\u00eda dele estava apenas em minha mem\u00f3ria &#8211; o que nunca foi um problema, mas fui ati\u00e7ada pela curiosidade. Ele me enviou algumas fotos, e junto das fotos do meu av\u00f4 havia uma foto com uma dedicat\u00f3ria \u00e0 minha av\u00f3, Jandyra, que tamb\u00e9m j\u00e1 faleceu h\u00e1 alguns anos. Era a foto de Dolores.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"2560\" height=\"1439\" src=\"https:\/\/i0.wp.com\/mulhervitrola.com.br\/blog\/wp-content\/uploads\/2023\/05\/IMG_20230503_090048251-scaled.jpg?resize=2560%2C1439&#038;ssl=1\" alt=\"Nelson de Ara\u00fajo Lima. Nova Igua\u00e7u, 1971. \" class=\"wp-image-16847\" srcset=\"https:\/\/i0.wp.com\/mulhervitrola.com.br\/blog\/wp-content\/uploads\/2023\/05\/IMG_20230503_090048251-scaled.jpg?w=2560&amp;ssl=1 2560w, https:\/\/i0.wp.com\/mulhervitrola.com.br\/blog\/wp-content\/uploads\/2023\/05\/IMG_20230503_090048251-scaled.jpg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/mulhervitrola.com.br\/blog\/wp-content\/uploads\/2023\/05\/IMG_20230503_090048251-scaled.jpg?resize=620%2C349&amp;ssl=1 620w, https:\/\/i0.wp.com\/mulhervitrola.com.br\/blog\/wp-content\/uploads\/2023\/05\/IMG_20230503_090048251-scaled.jpg?resize=768%2C432&amp;ssl=1 768w, https:\/\/i0.wp.com\/mulhervitrola.com.br\/blog\/wp-content\/uploads\/2023\/05\/IMG_20230503_090048251-scaled.jpg?resize=1536%2C864&amp;ssl=1 1536w, https:\/\/i0.wp.com\/mulhervitrola.com.br\/blog\/wp-content\/uploads\/2023\/05\/IMG_20230503_090048251-scaled.jpg?resize=2048%2C1152&amp;ssl=1 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><figcaption class=\"wp-element-caption\">Pintura \u00e0 \u00f3leo de Nelson de Ara\u00fajo Lima. Nova Igua\u00e7u, 1971.<\/figcaption><\/figure>\n\n\n\n<p class=\"has-text-align-justify\">N\u00e3o sei nada sobre Dolores, mas ela desapareceu. Quero dizer, a foto desapareceu. Eu a segurei durante um bom tempo em minhas m\u00e3os, analisei cada detalhe, cheguei at\u00e9 a devanear sobre Dolores e sua letra afetuosa, e de como o costume de presentear com fotos contendo dedicat\u00f3rias \u00e9 algo que eu ainda percorri e que agora acho que n\u00e3o existe mais. Ainda fazem dedicat\u00f3rias atr\u00e1s de fotos? Dar uma foto com dedicat\u00f3ria para algu\u00e9m at\u00e9 os anos 90 era sin\u00f4nimo de afeto e considera\u00e7\u00e3o. Ou, se fosse para um pretendente, era como se fosse uma esp\u00e9cie de &#8220;<em>superlike<\/em>&#8220;. Repousei a foto dentro de uma caixinha na estante de livros e Dolores desapareceu.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/i0.wp.com\/mulhervitrola.com.br\/blog\/wp-content\/uploads\/2023\/05\/Prancheta-3.jpg?resize=1920%2C1080&#038;ssl=1\" alt=\"\" class=\"wp-image-16852\" srcset=\"https:\/\/i0.wp.com\/mulhervitrola.com.br\/blog\/wp-content\/uploads\/2023\/05\/Prancheta-3.jpg?w=1920&amp;ssl=1 1920w, https:\/\/i0.wp.com\/mulhervitrola.com.br\/blog\/wp-content\/uploads\/2023\/05\/Prancheta-3.jpg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/mulhervitrola.com.br\/blog\/wp-content\/uploads\/2023\/05\/Prancheta-3.jpg?resize=620%2C349&amp;ssl=1 620w, https:\/\/i0.wp.com\/mulhervitrola.com.br\/blog\/wp-content\/uploads\/2023\/05\/Prancheta-3.jpg?resize=768%2C432&amp;ssl=1 768w, https:\/\/i0.wp.com\/mulhervitrola.com.br\/blog\/wp-content\/uploads\/2023\/05\/Prancheta-3.jpg?resize=1536%2C864&amp;ssl=1 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/figure>\n\n\n\n<p class=\"has-text-align-justify\">Pra n\u00e3o dizer que n\u00e3o falei de Dolores, ilustrei tudo que me lembro dela: sua dedicat\u00f3ria, seus cabelos, seus olhos muito negros e a pele p\u00e1lida. Acredito que Dolores vestia uma saia at\u00e9 abaixo dos joelhos, mas na foto apenas d\u00e1 pra ver que est\u00e1 vestindo uma blusa de um tecido que parecia muito leve e delicado, com um la\u00e7o de pontas longas no colarinho. Pra falar do Sr. Nelson, eu precisei pensar em Dolores. Se meu av\u00f4 estivesse vivo, certamente ele diria para eu confiar na minha mem\u00f3ria art\u00edstica. N\u00e3o sei se confio. Mas confio em dedicat\u00f3rias atr\u00e1s de fotografias.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para contar a hist\u00f3ria de Dolores, preciso contar antes sobre o Sr. Nelson. O Sr. Nelson era um artista de Nova Igua\u00e7u. Al\u00e9m de pintor de belos quadros, era professor de artes e idiomas. Apreciador de m\u00fasica espanhola e italiana e colecionador de discos de vinil. Tamb\u00e9m resgatava gatinhos de rua e todas as manh\u00e3s,&#8230;<a class=\"btnReadMore\" href=\"https:\/\/mulhervitrola.com.br\/blog\/dolores-sumiu\/\">Leia mais<i class=\"fa fa-long-arrow-right\"><\/i><\/a><\/p>\n","protected":false},"author":1,"featured_media":16852,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[122],"tags":[],"class_list":["post-16846","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-papo-de-vitrola"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Dolores sumiu. | Blog da Mulher Vitrola<\/title>\n<meta name=\"description\" content=\"Blog da ilustradora e gateira Re Vitrola. Veganismo, gatos e muita arte!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mulhervitrola.com.br\/blog\/dolores-sumiu\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dolores sumiu. | Blog da Mulher Vitrola\" \/>\n<meta property=\"og:description\" content=\"Blog da ilustradora e gateira Re Vitrola. Veganismo, gatos e muita arte!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mulhervitrola.com.br\/blog\/dolores-sumiu\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog da Mulher Vitrola\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-03T14:57:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-03T14:57:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mulhervitrola.com.br\/blog\/wp-content\/uploads\/2023\/05\/Prancheta-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mulhervitrola\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@mulhervitrola\" \/>\n<meta name=\"twitter:site\" content=\"@mulhervitrola\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"mulhervitrola\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/mulhervitrola.com.br\/blog\/dolores-sumiu\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/mulhervitrola.com.br\/blog\/dolores-sumiu\/\"},\"author\":{\"name\":\"mulhervitrola\",\"@id\":\"https:\/\/mulhervitrola.com.br\/blog\/#\/schema\/person\/df88e61e635561444a7aca4ca394ed85\"},\"headline\":\"Dolores sumiu.\",\"datePublished\":\"2023-05-03T14:57:03+00:00\",\"dateModified\":\"2023-05-03T14:57:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/mulhervitrola.com.br\/blog\/dolores-sumiu\/\"},\"wordCount\":689,\"commentCount\":3,\"publisher\":{\"@id\":\"https:\/\/mulhervitrola.com.br\/blog\/#\/schema\/person\/df88e61e635561444a7aca4ca394ed85\"},\"image\":{\"@id\":\"https:\/\/mulhervitrola.com.br\/blog\/dolores-sumiu\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/i0.wp.com\/mulhervitrola.com.br\/blog\/wp-content\/uploads\/2023\/05\/Prancheta-3.jpg?fit=1920%2C1080&ssl=1\",\"articleSection\":[\"Papo de Vitrola\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/mulhervitrola.com.br\/blog\/dolores-sumiu\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/mulhervitrola.com.br\/blog\/dolores-sumiu\/\",\"url\":\"https:\/\/mulhervitrola.com.br\/blog\/dolores-sumiu\/\",\"name\":\"Dolores sumiu. | Blog da Mulher Vitrola\",\"isPartOf\":{\"@id\":\"https:\/\/mulhervitrola.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/mulhervitrola.com.br\/blog\/dolores-sumiu\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/mulhervitrola.com.br\/blog\/dolores-sumiu\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/i0.wp.com\/mulhervitrola.com.br\/blog\/wp-content\/uploads\/2023\/05\/Prancheta-3.jpg?fit=1920%2C1080&ssl=1\",\"datePublished\":\"2023-05-03T14:57:03+00:00\",\"dateModified\":\"2023-05-03T14:57:08+00:00\",\"description\":\"Blog da ilustradora e gateira Re Vitrola. Veganismo, gatos e muita arte!\",\"breadcrumb\":{\"@id\":\"https:\/\/mulhervitrola.com.br\/blog\/dolores-sumiu\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/mulhervitrola.com.br\/blog\/dolores-sumiu\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/mulhervitrola.com.br\/blog\/dolores-sumiu\/#primaryimage\",\"url\":\"https:\/\/i0.wp.com\/mulhervitrola.com.br\/blog\/wp-content\/uploads\/2023\/05\/Prancheta-3.jpg?fit=1920%2C1080&ssl=1\",\"contentUrl\":\"https:\/\/i0.wp.com\/mulhervitrola.com.br\/blog\/wp-content\/uploads\/2023\/05\/Prancheta-3.jpg?fit=1920%2C1080&ssl=1\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/mulhervitrola.com.br\/blog\/dolores-sumiu\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/mulhervitrola.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dolores sumiu.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mulhervitrola.com.br\/blog\/#website\",\"url\":\"https:\/\/mulhervitrola.com.br\/blog\/\",\"name\":\"Blog da Mulher Vitrola\",\"description\":\"por Re Montenegro\",\"publisher\":{\"@id\":\"https:\/\/mulhervitrola.com.br\/blog\/#\/schema\/person\/df88e61e635561444a7aca4ca394ed85\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mulhervitrola.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\/\/mulhervitrola.com.br\/blog\/#\/schema\/person\/df88e61e635561444a7aca4ca394ed85\",\"name\":\"mulhervitrola\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/mulhervitrola.com.br\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/i0.wp.com\/mulhervitrola.com.br\/wp-content\/uploads\/2020\/05\/DSC_0200-scaled.jpg?fit=2560%2C1702&ssl=1\",\"contentUrl\":\"https:\/\/i0.wp.com\/mulhervitrola.com.br\/wp-content\/uploads\/2020\/05\/DSC_0200-scaled.jpg?fit=2560%2C1702&ssl=1\",\"width\":2560,\"height\":1702,\"caption\":\"mulhervitrola\"},\"logo\":{\"@id\":\"https:\/\/mulhervitrola.com.br\/blog\/#\/schema\/person\/image\/\"},\"sameAs\":[\"mulhervitrola\"],\"url\":\"https:\/\/mulhervitrola.com.br\/blog\/author\/mulhervitrola\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dolores sumiu. | Blog da Mulher Vitrola","description":"Blog da ilustradora e gateira Re Vitrola. Veganismo, gatos e muita arte!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mulhervitrola.com.br\/blog\/dolores-sumiu\/","og_locale":"pt_BR","og_type":"article","og_title":"Dolores sumiu. | Blog da Mulher Vitrola","og_description":"Blog da ilustradora e gateira Re Vitrola. Veganismo, gatos e muita arte!","og_url":"https:\/\/mulhervitrola.com.br\/blog\/dolores-sumiu\/","og_site_name":"Blog da Mulher Vitrola","article_published_time":"2023-05-03T14:57:03+00:00","article_modified_time":"2023-05-03T14:57:08+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/mulhervitrola.com.br\/blog\/wp-content\/uploads\/2023\/05\/Prancheta-3.jpg","type":"image\/jpeg"}],"author":"mulhervitrola","twitter_card":"summary_large_image","twitter_creator":"@mulhervitrola","twitter_site":"@mulhervitrola","twitter_misc":{"Escrito por":"mulhervitrola","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mulhervitrola.com.br\/blog\/dolores-sumiu\/#article","isPartOf":{"@id":"https:\/\/mulhervitrola.com.br\/blog\/dolores-sumiu\/"},"author":{"name":"mulhervitrola","@id":"https:\/\/mulhervitrola.com.br\/blog\/#\/schema\/person\/df88e61e635561444a7aca4ca394ed85"},"headline":"Dolores sumiu.","datePublished":"2023-05-03T14:57:03+00:00","dateModified":"2023-05-03T14:57:08+00:00","mainEntityOfPage":{"@id":"https:\/\/mulhervitrola.com.br\/blog\/dolores-sumiu\/"},"wordCount":689,"commentCount":3,"publisher":{"@id":"https:\/\/mulhervitrola.com.br\/blog\/#\/schema\/person\/df88e61e635561444a7aca4ca394ed85"},"image":{"@id":"https:\/\/mulhervitrola.com.br\/blog\/dolores-sumiu\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/mulhervitrola.com.br\/blog\/wp-content\/uploads\/2023\/05\/Prancheta-3.jpg?fit=1920%2C1080&ssl=1","articleSection":["Papo de Vitrola"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/mulhervitrola.com.br\/blog\/dolores-sumiu\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/mulhervitrola.com.br\/blog\/dolores-sumiu\/","url":"https:\/\/mulhervitrola.com.br\/blog\/dolores-sumiu\/","name":"Dolores sumiu. | Blog da Mulher Vitrola","isPartOf":{"@id":"https:\/\/mulhervitrola.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mulhervitrola.com.br\/blog\/dolores-sumiu\/#primaryimage"},"image":{"@id":"https:\/\/mulhervitrola.com.br\/blog\/dolores-sumiu\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/mulhervitrola.com.br\/blog\/wp-content\/uploads\/2023\/05\/Prancheta-3.jpg?fit=1920%2C1080&ssl=1","datePublished":"2023-05-03T14:57:03+00:00","dateModified":"2023-05-03T14:57:08+00:00","description":"Blog da ilustradora e gateira Re Vitrola. Veganismo, gatos e muita arte!","breadcrumb":{"@id":"https:\/\/mulhervitrola.com.br\/blog\/dolores-sumiu\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mulhervitrola.com.br\/blog\/dolores-sumiu\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/mulhervitrola.com.br\/blog\/dolores-sumiu\/#primaryimage","url":"https:\/\/i0.wp.com\/mulhervitrola.com.br\/blog\/wp-content\/uploads\/2023\/05\/Prancheta-3.jpg?fit=1920%2C1080&ssl=1","contentUrl":"https:\/\/i0.wp.com\/mulhervitrola.com.br\/blog\/wp-content\/uploads\/2023\/05\/Prancheta-3.jpg?fit=1920%2C1080&ssl=1","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/mulhervitrola.com.br\/blog\/dolores-sumiu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/mulhervitrola.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Dolores sumiu."}]},{"@type":"WebSite","@id":"https:\/\/mulhervitrola.com.br\/blog\/#website","url":"https:\/\/mulhervitrola.com.br\/blog\/","name":"Blog da Mulher Vitrola","description":"por Re Montenegro","publisher":{"@id":"https:\/\/mulhervitrola.com.br\/blog\/#\/schema\/person\/df88e61e635561444a7aca4ca394ed85"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mulhervitrola.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":["Person","Organization"],"@id":"https:\/\/mulhervitrola.com.br\/blog\/#\/schema\/person\/df88e61e635561444a7aca4ca394ed85","name":"mulhervitrola","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/mulhervitrola.com.br\/blog\/#\/schema\/person\/image\/","url":"https:\/\/i0.wp.com\/mulhervitrola.com.br\/wp-content\/uploads\/2020\/05\/DSC_0200-scaled.jpg?fit=2560%2C1702&ssl=1","contentUrl":"https:\/\/i0.wp.com\/mulhervitrola.com.br\/wp-content\/uploads\/2020\/05\/DSC_0200-scaled.jpg?fit=2560%2C1702&ssl=1","width":2560,"height":1702,"caption":"mulhervitrola"},"logo":{"@id":"https:\/\/mulhervitrola.com.br\/blog\/#\/schema\/person\/image\/"},"sameAs":["mulhervitrola"],"url":"https:\/\/mulhervitrola.com.br\/blog\/author\/mulhervitrola\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/mulhervitrola.com.br\/blog\/wp-content\/uploads\/2023\/05\/Prancheta-3.jpg?fit=1920%2C1080&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p3GuHo-4nI","jetpack-related-posts":[{"id":8750,"url":"https:\/\/mulhervitrola.com.br\/blog\/collab-vah-andrade-os-peixes\/","url_meta":{"origin":16846,"position":0},"title":"Collab Vah Andrade: Os Peixes","author":"mulhervitrola","date":"15 de agosto de 2018","format":false,"excerpt":"Collab - Os Peixes, por Vah Andrade e Re Vitrola Fazia muito tempo que queria fazer um trabalho colaborativo com algu\u00e9m, planejei no in\u00edcio do ano com minha amiga talentosa e jornalista Vah Andrade nem de longe eu fazia ideia que seria t\u00e3o fant\u00e1stico! Um collab parece algo simples, mas\u2026","rel":"","context":"Em &quot;Papo de Artista&quot;","block_context":{"text":"Papo de Artista","link":"https:\/\/mulhervitrola.com.br\/blog\/category\/papodeartista\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/mulhervitrola.com.br\/wp-content\/uploads\/2018\/08\/SAM_1157.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":17822,"url":"https:\/\/mulhervitrola.com.br\/blog\/mae-de-adulto\/","url_meta":{"origin":16846,"position":1},"title":"M\u00e3e de adulto","author":"mulhervitrola","date":"22 de janeiro de 2026","format":false,"excerpt":"Uma m\u00e3e de um adulto entra na sala... em que se converte a mater tem a nos dizer depois que nos tornamos \"dispens\u00e1veis\"?","rel":"","context":"Em &quot;Papo de Vitrola&quot;","block_context":{"text":"Papo de Vitrola","link":"https:\/\/mulhervitrola.com.br\/blog\/category\/papo-de-vitrola\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/mulhervitrola.com.br\/blog\/wp-content\/uploads\/2026\/01\/Ilustra-Renata-Montenegro.psd.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/mulhervitrola.com.br\/blog\/wp-content\/uploads\/2026\/01\/Ilustra-Renata-Montenegro.psd.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/mulhervitrola.com.br\/blog\/wp-content\/uploads\/2026\/01\/Ilustra-Renata-Montenegro.psd.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/mulhervitrola.com.br\/blog\/wp-content\/uploads\/2026\/01\/Ilustra-Renata-Montenegro.psd.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/mulhervitrola.com.br\/blog\/wp-content\/uploads\/2026\/01\/Ilustra-Renata-Montenegro.psd.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":1934,"url":"https:\/\/mulhervitrola.com.br\/blog\/vida-sem-propositos\/","url_meta":{"origin":16846,"position":2},"title":"A beleza de uma vida sem prop\u00f3sitos","author":"mulhervitrola","date":"19 de outubro de 2013","format":false,"excerpt":"Quando eu tinha uns cinco anos eu conheci meu av\u00f4 Nelson, que na verdade era padrasto do meu pai. Nos identificamos de imediato, mesmo sem nenhum grau sangu\u00edneo de parentesco: ele fazia bel\u00edssimas telas de pintura \u00e0 \u00f3leo (e tamb\u00e9m dava aulas), falava v\u00e1rios idiomas, amava gatos e adorava m\u00fasica\u2026","rel":"","context":"Em &quot;Papo de Vitrola&quot;","block_context":{"text":"Papo de Vitrola","link":"https:\/\/mulhervitrola.com.br\/blog\/category\/papo-de-vitrola\/"},"img":{"alt_text":"My-Strange-Grandfather","src":"https:\/\/i0.wp.com\/mulhervitrola.com.br\/wp-content\/uploads\/2013\/10\/My-Strange-Grandfather.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/mulhervitrola.com.br\/wp-content\/uploads\/2013\/10\/My-Strange-Grandfather.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/mulhervitrola.com.br\/wp-content\/uploads\/2013\/10\/My-Strange-Grandfather.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/mulhervitrola.com.br\/wp-content\/uploads\/2013\/10\/My-Strange-Grandfather.jpg?resize=700%2C400 2x"},"classes":[]},{"id":142,"url":"https:\/\/mulhervitrola.com.br\/blog\/bom-mesmo-e-o-comecinho\/","url_meta":{"origin":16846,"position":3},"title":"Bom mesmo \u00e9 o comecinho!","author":"mulhervitrola","date":"5 de mar\u00e7o de 2012","format":false,"excerpt":"Parece que foi ontem que celular era para poucos n\u00e3o \u00e9 mesmo? E foi. Embora sempre tentando me manter ligada no \"novo\", tenho sempre receio de estar perdida nesse tiroteio tecnol\u00f3gico. At\u00e9 \"ontem\" eu colocava um walkman na cintura, acompanhava as m\u00fasicas pelos encartes do disco e meu celular, bem\u2026","rel":"","context":"Em &quot;Papo de Vitrola&quot;","block_context":{"text":"Papo de Vitrola","link":"https:\/\/mulhervitrola.com.br\/blog\/category\/papo-de-vitrola\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8143,"url":"https:\/\/mulhervitrola.com.br\/blog\/sobre-val\/","url_meta":{"origin":16846,"position":4},"title":"Eu s\u00f3 vim falar sobre a Val","author":"mulhervitrola","date":"16 de setembro de 2016","format":false,"excerpt":"Antes de qualquer coisa, essa postagem n\u00e3o tem nenhum fundo moral\u00a0ou de \"lacre\". Eu s\u00f3 vim falar sobre a\u00a0Val. \u00a0 Conheci a Val quando eu tinha 14\/15 anos. Ela sabia que eu amava ler e estudar, ent\u00e3o sempre me dava algum livro. A Val usava o cabelo curtinho e fazia\u2026","rel":"","context":"Em &quot;Papo de Vitrola&quot;","block_context":{"text":"Papo de Vitrola","link":"https:\/\/mulhervitrola.com.br\/blog\/category\/papo-de-vitrola\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/mulhervitrola.com.br\/blog\/wp-content\/uploads\/2016\/09\/val.jpg?fit=780%2C1200&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/mulhervitrola.com.br\/blog\/wp-content\/uploads\/2016\/09\/val.jpg?fit=780%2C1200&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/mulhervitrola.com.br\/blog\/wp-content\/uploads\/2016\/09\/val.jpg?fit=780%2C1200&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/mulhervitrola.com.br\/blog\/wp-content\/uploads\/2016\/09\/val.jpg?fit=780%2C1200&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":16722,"url":"https:\/\/mulhervitrola.com.br\/blog\/cem-cafezinhos-antes-do-sol-nascer\/","url_meta":{"origin":16846,"position":5},"title":"Cem cafezinhos antes do sol nascer","author":"mulhervitrola","date":"5 de abril de 2023","format":false,"excerpt":"Antes dos meus pais terem o bar, minha m\u00e3e trabalhou muitos anos como camel\u00f4 na passarela debaixo da esta\u00e7\u00e3o de trem do Gramacho, um bairro aqui de Duque de Caxias, o mesmo do famoso document\u00e1rio \"Lixo Extraordin\u00e1rio\". Ela acordava muito antes do que qualquer pessoa que trabalha muito cedo acordava,\u2026","rel":"","context":"Em &quot;Papo de Vitrola&quot;","block_context":{"text":"Papo de Vitrola","link":"https:\/\/mulhervitrola.com.br\/blog\/category\/papo-de-vitrola\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/mulhervitrola.com.br\/blog\/wp-content\/uploads\/2023\/04\/cafezinho-da-madrugada-mulhervitrolaPrancheta-1.jpg?fit=980%2C649&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/mulhervitrola.com.br\/blog\/wp-content\/uploads\/2023\/04\/cafezinho-da-madrugada-mulhervitrolaPrancheta-1.jpg?fit=980%2C649&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/mulhervitrola.com.br\/blog\/wp-content\/uploads\/2023\/04\/cafezinho-da-madrugada-mulhervitrolaPrancheta-1.jpg?fit=980%2C649&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/mulhervitrola.com.br\/blog\/wp-content\/uploads\/2023\/04\/cafezinho-da-madrugada-mulhervitrolaPrancheta-1.jpg?fit=980%2C649&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/mulhervitrola.com.br\/blog\/wp-json\/wp\/v2\/posts\/16846","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mulhervitrola.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mulhervitrola.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mulhervitrola.com.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mulhervitrola.com.br\/blog\/wp-json\/wp\/v2\/comments?post=16846"}],"version-history":[{"count":5,"href":"https:\/\/mulhervitrola.com.br\/blog\/wp-json\/wp\/v2\/posts\/16846\/revisions"}],"predecessor-version":[{"id":16854,"href":"https:\/\/mulhervitrola.com.br\/blog\/wp-json\/wp\/v2\/posts\/16846\/revisions\/16854"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mulhervitrola.com.br\/blog\/wp-json\/wp\/v2\/media\/16852"}],"wp:attachment":[{"href":"https:\/\/mulhervitrola.com.br\/blog\/wp-json\/wp\/v2\/media?parent=16846"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mulhervitrola.com.br\/blog\/wp-json\/wp\/v2\/categories?post=16846"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mulhervitrola.com.br\/blog\/wp-json\/wp\/v2\/tags?post=16846"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}